{"id":1705,"date":"2026-05-06T14:56:33","date_gmt":"2026-05-06T20:56:33","guid":{"rendered":"https:\/\/wyoextension.org\/johnsoncounty\/?post_type=mec-events&#038;p=1705"},"modified":"2026-05-06T14:56:33","modified_gmt":"2026-05-06T20:56:33","slug":"4-h-first-time-livestock-seller-meeting","status":"publish","type":"mec-events","link":"https:\/\/wyoextension.org\/johnsoncounty\/events\/4-h-first-time-livestock-seller-meeting\/","title":{"rendered":"4-H First Time Livestock Seller Meeting"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","tags":[],"mec_category":[28],"class_list":["post-1705","mec-events","type-mec-events","status-publish","hentry","mec_category-4-h"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/wyoextension.org\/johnsoncounty\/wp-json\/wp\/v2\/mec-events\/1705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wyoextension.org\/johnsoncounty\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/wyoextension.org\/johnsoncounty\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/wyoextension.org\/johnsoncounty\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/wyoextension.org\/johnsoncounty\/wp-json\/wp\/v2\/comments?post=1705"}],"wp:attachment":[{"href":"https:\/\/wyoextension.org\/johnsoncounty\/wp-json\/wp\/v2\/media?parent=1705"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wyoextension.org\/johnsoncounty\/wp-json\/wp\/v2\/tags?post=1705"},{"taxonomy":"mec_category","embeddable":true,"href":"https:\/\/wyoextension.org\/johnsoncounty\/wp-json\/wp\/v2\/mec_category?post=1705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}